{"id":10418,"date":"2022-07-24T09:28:59","date_gmt":"2022-07-24T01:28:59","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=10418"},"modified":"2022-08-17T15:33:16","modified_gmt":"2022-08-17T07:33:16","slug":"20191019_50%e6%a8%82%e9%bd%a1%e9%81%8a%e4%b9%8b%e5%a4%a7%e6%b2%99%e6%b2%b3%e5%85%ac%e5%9c%92","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10418\/","title":{"rendered":"20191019_50+\u6a02\u9f61\u904a\u4e4b\u5927\u6c99\u6cb3\u516c\u5712_\u8993\u98df\u8da3\u7f8e\u98df\u57ce_\u842c\u8c61\u5929\u5730"},"content":{"rendered":"\n<p>50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u5927\u6c99\u6cb3\u516c\u5712(2019\u5e7410\u670819\u65e5)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"NS96uMeIPT\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10353\/\">50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u5927\u6c99\u6cb3\u516c\u5712(2019\u5e7410\u670819\u65e5)<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u5927\u6c99\u6cb3\u516c\u5712(2019\u5e7410\u670819\u65e5)\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10353\/embed\/#?secret=IgP3hv7A7r#?secret=NS96uMeIPT\" data-secret=\"NS96uMeIPT\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>50+\u6a02\u9f61\u904a\u4e4b\u8993\u98df\u8da3\u7f8e\u98df\u57ce(2019\u5e7410\u670819\u65e5)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"jAzJB6ZzcA\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10367\/\">50+\u6a02\u9f61\u904a\u4e4b\u8993\u98df\u8da3\u7f8e\u98df\u57ce(2019\u5e7410\u670819\u65e5)<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c50+\u6a02\u9f61\u904a\u4e4b\u8993\u98df\u8da3\u7f8e\u98df\u57ce(2019\u5e7410\u670819\u65e5)\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10367\/embed\/#?secret=cJwQuG3hx2#?secret=jAzJB6ZzcA\" data-secret=\"jAzJB6ZzcA\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u842c\u8c61\u5929\u5730(2019\u5e7410\u670819\u65e5)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"3x1msORby2\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10384\/\">50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u842c\u8c61\u5929\u5730(2019\u5e7410\u670819\u65e5)<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u842c\u8c61\u5929\u5730(2019\u5e7410\u670819\u65e5)\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10384\/embed\/#?secret=jwJxM5hxnH#?secret=3x1msORby2\" data-secret=\"3x1msORby2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u767d\u77f3\u9f8d\u7ad9\u96f2\u5473\u9928(2019\u5e7410\u670819\u65e5)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"g85LmxmpAw\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10401\/\">50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u767d\u77f3\u9f8d\u7ad9\u96f2\u5473\u9928(2019\u5e7410\u670819\u65e5)<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c50+\u6a02\u9f61\u904a\u4e4b\u6df1\u5733\u767d\u77f3\u9f8d\u7ad9\u96f2\u5473\u9928(2019\u5e7410\u670819\u65e5)\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/10401\/embed\/#?secret=5RiBYW4Dso#?secret=g85LmxmpAw\" data-secret=\"g85LmxmpAw\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p>Views: 38<\/p>","protected":false},"excerpt":{"rendered":"<p>20191019_50+\u6a02\u9f61\u904a\u4e4b\u5927\u6c99\u6cb3\u516c\u5712_\u8993\u98df\u8da3\u7f8e\u98df\u57ce_\u842c\u8c61\u5929\u5730<\/p>\n","protected":false},"author":1,"featured_media":10361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-50-travelling"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/10418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=10418"}],"version-history":[{"count":2,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/10418\/revisions"}],"predecessor-version":[{"id":11942,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/10418\/revisions\/11942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/10361"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=10418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=10418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=10418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}