{"id":10497,"date":"2022-07-25T21:33:00","date_gmt":"2022-07-25T13:33:00","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=10497"},"modified":"2022-07-25T21:33:01","modified_gmt":"2022-07-25T13:33:01","slug":"50%e9%a6%99%e6%b8%af%e8%a1%8c%e4%b9%8b%e5%a4%a7%e8%a0%94%e7%81%a32022%e5%b9%b47%e6%9c%8822%e6%97%a5","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/50-hk-travel\/10497\/","title":{"rendered":"50+\u9999\u6e2f\u884c\u4e4b\u5927\u8814\u7063(2022\u5e747\u670822\u65e5)"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_01.jpg\" alt=\"\" data-id=\"10498\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_01.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10498\" class=\"wp-image-10498\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_01.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_01-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_01-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_02.jpg\" alt=\"\" data-id=\"10499\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_02.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10499\" class=\"wp-image-10499\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_02.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_02-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_02-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_03.jpg\" alt=\"\" data-id=\"10500\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_03.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10500\" class=\"wp-image-10500\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_03.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_03-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_03-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_04.jpg\" alt=\"\" data-id=\"10501\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_04.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10501\" class=\"wp-image-10501\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_04.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_04-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_04-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_05.jpg\" alt=\"\" data-id=\"10502\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_05.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10502\" class=\"wp-image-10502\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_05.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_05-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_05-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"has-drop-cap has-light-green-cyan-background-color has-background\">\u767d\u8292\u6751\u4f4d\u8655\u5927\u8814\u7063\uff0c\u800c\u6700\u8b93\u9999\u6e2f\u4eba\u719f\u6089\u7684\u83ab\u904e\u65bc\u6d77\u5cb8\u53e6\u4e00\u7aef\u7684\u6e2f\u73e0\u6fb3\u5927\u6a4b\u9999\u6e2f\u53e3\u5cb8\u4eba\u5de5\u5cf6\uff0c\u4ee5\u53ca\u6bd7\u9130\u7684\u8d64\u9c72\u89d2\u6a5f\u5834\u3002\u6b64\u6642\uff0c\u5927\u8814\u7063\u8207\u4eba\u5de5\u5cf6\u53e3\u5cb8\u9023\u63a5\u7684\u9806\u6717\u8def\u884c\u8eca\u5929\u6a4b\u5012\u5f71\uff0c\u5e73\u975c\u5730\u8eba\u5728\u53f3\u5074\u7684\u6c34\u9762\u4e0a\uff0c\u69cb\u6210\u660e\u5a9a\u5982\u756b\u7684\u6e56\u7554\u98a8\u5149\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_06.jpg\" alt=\"\" data-id=\"10503\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_06.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10503\" class=\"wp-image-10503\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_06.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_06-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_06-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_07.jpg\" alt=\"\" data-id=\"10504\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_07.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10504\" class=\"wp-image-10504\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_07.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_07-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_07-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_08.jpg\" alt=\"\" data-id=\"10505\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_08.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10505\" class=\"wp-image-10505\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_08.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_08-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_08-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_09.jpg\" alt=\"\" data-id=\"10506\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_09.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10506\" class=\"wp-image-10506\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_09.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_09-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_09-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_10.jpg\" alt=\"\" data-id=\"10507\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_10.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10507\" class=\"wp-image-10507\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_10.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_10-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_10-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"has-drop-cap has-light-green-cyan-background-color has-background\">\u767d\u8292\u6751\u4e00\u6bb5\u7684\u5967\u904b\u5f91\u53ef\u6cbf\u5c71\u8170\u800c\u884c\u76f4\u9054\u6771\u6d8c\u65b0\u5e02\u93ae\uff0c\u68c4\u4e4b\u6539\u884c\u6d77\u65c1\u5c0f\u8def\uff0c\u8c48\u6599\u7a7f\u904e\u884c\u4eba\u96a7\u9053\u5f8c\u5168\u662f\u6c99\u5875\u6efe\u6efe\u7684\u5de5\u5730\u3002\u56e0\u61c9\u9019\u7247\u586b\u6d77\u7528\u5730\u5df2\u5217\u70ba\u6771\u6d8c\u6771\u65b0\u64f4\u5c55\u5340\uff0c\u4e26\u589e\u8a2d\u6e2f\u9435\u6771\u6d8c\u6771\u9ad8\u67b6\u8eca\u7ad9\uff0c\u52a0\u4e0a\u9700\u8d95\u53ca2029\u5b8c\u5de5\u7684\u6642\u9593\u8868\uff0c\u7e31\u7136\u662f\u70c8\u65e5\u4e0b\uff0c\u5927\u578b\u8eca\u8f1b\u4ecd\u4e0d\u65b7\u7a7f\u68b3\u5f80\u4f86\uff0c\u5c0e\u81f4\u8def\u4e0a\u5875\u571f\u4e0d\u7d55\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_11.jpg\" alt=\"\" data-id=\"10508\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_11.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10508\" class=\"wp-image-10508\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_11.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_11-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_11-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_12.jpg\" alt=\"\" data-id=\"10509\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_12.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10509\" class=\"wp-image-10509\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_12.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_12-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_12-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_13.jpg\" alt=\"\" data-id=\"10510\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_13.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10510\" class=\"wp-image-10510\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_13.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_13-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_13-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_14.jpg\" alt=\"\" data-id=\"10511\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_14.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10511\" class=\"wp-image-10511\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_14.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_14-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_14-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_15.jpg\" alt=\"\" data-id=\"10512\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_15.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=10512\" class=\"wp-image-10512\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_15.jpg 800w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_15-300x200.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/07\/20220722_\u5927\u8814\u7063_15-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><\/figure>\n<p>Views: 60<\/p>","protected":false},"excerpt":{"rendered":"<p>\u56e0\u61c9\u9019\u7247\u586b\u6d77\u7528\u5730\u5df2\u5217\u70ba\u6771\u6d8c\u6771\u65b0\u64f4\u5c55\u5340\uff0c\u4e26\u589e\u8a2d\u6e2f\u9435\u6771\u6d8c\u6771\u9ad8\u67b6\u8eca\u7ad9\uff0c\u52a0\u4e0a\u9700\u8d95\u53ca2029\u5b8c\u5de5\u7684\u6642\u9593\u8868\uff0c\u7e31\u7136\u662f\u70c8\u65e5\u4e0b\uff0c\u5927\u578b\u8eca\u8f1b\u4ecd\u4e0d\u65b7\u7a7f\u68b3\u5f80\u4f86\uff0c\u5c0e\u81f4\u8def\u4e0a\u5875\u571f\u4e0d\u7d55\u3002<\/p>\n","protected":false},"author":1,"featured_media":10500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[77,3,2],"tags":[],"class_list":["post-10497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2022_","category-2022_50-hk-travel","category-50-hk-travel"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/10497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=10497"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/10497\/revisions"}],"predecessor-version":[{"id":10513,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/10497\/revisions\/10513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/10500"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=10497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=10497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=10497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}