{"id":12898,"date":"2022-08-31T16:04:34","date_gmt":"2022-08-31T08:04:34","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=12898"},"modified":"2022-08-31T16:04:35","modified_gmt":"2022-08-31T08:04:35","slug":"50%e6%a8%82%e9%bd%a1%e9%81%8a%e4%b9%8b%e5%8d%97%e5%af%a7%e8%a1%8c%e7%ac%ac%e4%b8%80%e5%a4%a9%e5%bb%a3%e5%b7%9e%e5%8d%97%e7%ab%99%e8%bd%89%e8%bb%8a%e9%ab%94%e9%a9%972019%e5%b9%b44%e6%9c%8819","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/50-travelling\/12898\/","title":{"rendered":"50+\u6a02\u9f61\u904a\u4e4b\u5357\u5be7\u884c\u7b2c\u4e00\u5929(\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca\u9ad4\u9a57)(2019\u5e744\u670819\u65e5)"},"content":{"rendered":"\n<p class=\"has-drop-cap has-light-green-cyan-background-color has-background\">0847\u6642\u6df1\u5733\u5317\u7ad9\u958b\u51fa\uff0c\u62b5\u9054\u9ad8\u9435\u5ee3\u5dde\u5357\u7ad9\u6642\u9593\u70ba0923\u6642\u3002\u53ea\u670930\u591a\u5206\u9418\u7684\u8eca\u7a0b\uff0c\u53ef\u8aaa\u662f\u8f49\u773c\u904e\u53bb\uff0c\u8db3\u8b49\u5167\u5730\u9ad8\u901f\u9435\u8def\u767c\u5c55\uff0c\u69cb\u5efa\u5927\u7063\u5340\u4e00\u5c0f\u6642\u751f\u6d3b\u5708\uff0c\u5c0d\u5340\u5167\u6c11\u773e\u5e36\u4f86\u6975\u5927\u4fbf\u5229\u6027\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_01.jpg\" alt=\"\" data-id=\"12899\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_01.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12899\" class=\"wp-image-12899\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_01.jpg 960w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_01-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_02.jpg\" alt=\"\" data-id=\"12900\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_02.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12900\" class=\"wp-image-12900\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_02.jpg 960w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_02-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_03-1024x512.jpg\" alt=\"\" data-id=\"12901\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_03.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12901\" class=\"wp-image-12901\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_03-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_03-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_03-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_03.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"has-drop-cap has-light-green-cyan-background-color has-background\">\u5ee3\u5dde\u5357\u7ad9\u662f\u5ee3\u6771\u7701\u91cd\u8981\u7684\u4ea4\u901a\u6a1e\u7d10\uff0c\u5e7e\u4e4e\u6bcf\u6642\u6bcf\u523b\u90fd\u6709\u4f86\u81ea\u6216\u524d\u5f80\u6771\u5357\u897f\u5317\u56db\u500b\u65b9\u5411\u7684\u5217\u8eca\u62b5\u9054\u6216\u96e2\u958b\uff0c\u642d\u8f09\u6578\u4ee5\u842c\u8a08\u7684\u65c5\u5ba2\u524d\u5f80\u4e0d\u540c\u7684\u76ee\u7684\u5730\u3002\u8207\u8001\u4f34\u642d\u4e58\u9ad8\u9435\u591a\u6b21\uff0c\u4f46\u7ad9\u5167\u8f49\u8eca\u5c1a\u5c6c\u9996\u6b21\u3002\u5e78\u800c\u4e0b\u8eca\u5f8c\u6709\u6e05\u6670\u660e\u78ba\u7684\u6307\u793a\uff0c\u6cbf\u6a13\u68af\uff08\u6216\u6276\u624b\u96fb\u68af\uff09\u76f4\u4e0a\u4e0d\u75283\u5206\u9418\uff0c\u4fbf\u5230\u9054\u5019\u8eca\u5927\u5802\uff0c\u6bcb\u9808\u518d\u63a5\u53d7\u5b89\u6aa2\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_04.jpg\" alt=\"\" data-id=\"12902\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_04.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12902\" class=\"wp-image-12902\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_04.jpg 960w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_04-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_05-1024x512.jpg\" alt=\"\" data-id=\"12903\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_05.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12903\" class=\"wp-image-12903\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_05-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_05-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_05-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_05.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_06-1024x512.jpg\" alt=\"\" data-id=\"12904\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_06.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12904\" class=\"wp-image-12904\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_06-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_06-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_06-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_06.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_07-1024x512.jpg\" alt=\"\" data-id=\"12905\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_07.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12905\" class=\"wp-image-12905\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_07-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_07-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_07-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_07.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_08-1024x512.jpg\" alt=\"\" data-id=\"12906\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_08.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12906\" class=\"wp-image-12906\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_08-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_08-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_08-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_08.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"has-drop-cap has-light-green-cyan-background-color has-background\">\u555f\u7a0b\u524d\uff0c\u500b\u4eba\u8ddf\u5f9e\u9ad8\u9435\u7db2\u7ad9\u52f8\u55bb\uff0c\u9810\u755930\u5206\u9418\u8f49\u8eca\u6642\u9593\u3002\u96d6\u7136\u9084\u670920\u591a\u5206\u9418\u624d\u662f\u5f80\u5357\u5be7\u6771\u5217\u8eca\u7684\u767c\u8eca\uff0c\u6642\u9593\u770b\u4f86\u9084\u6709\u5f88\u591a\uff0c\u4f46\u82b1\u5c11\u8a31\u6642\u9593\u7528\u4f86\u6838\u5c0d\u767b\u8eca\u6708\u53f0\u4f4d\u7f6e\uff0c\u518d\u53bb\u4e00\u8d9f\u6d17\u624b\u9593\uff0c\u4fbf\u5dee\u4e0d\u591a\u662f\u958b\u653e\u9598\u53e3\u9032\u5165\u6708\u53f0\u524d\u768415\u5206\u9418\u6642\u9593\u3002\u56e0\u6b64\u9810\u755930\u5206\u9418\u662f\u5fc5\u9808\u7684\uff0c\u82e5\u7136\u5217\u8eca\u7a0d\u70ba\u8aa4\u9ede\u6578\u5206\u9418\uff0c\u9084\u53ef\u8d95\u5f97\u53ca\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_09-1024x512.jpg\" alt=\"\" data-id=\"12907\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_09.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12907\" class=\"wp-image-12907\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_09-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_09-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_09-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_09.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_10-1024x512.jpg\" alt=\"\" data-id=\"12908\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_10.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12908\" class=\"wp-image-12908\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_10-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_10-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_10-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_10.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_11-1024x512.jpg\" alt=\"\" data-id=\"12909\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_11.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12909\" class=\"wp-image-12909\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_11-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_11-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_11-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_11.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_12-1024x512.jpg\" alt=\"\" data-id=\"12910\" data-full-url=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_12.jpg\" data-link=\"https:\/\/50pluslifestories.synology.me\/wordpress\/?attachment_id=12910\" class=\"wp-image-12910\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_12-1024x512.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_12-300x150.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_12-768x384.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/2022\/08\/20190419_\u5ee3\u5dde\u5357\u7ad9\u8f49\u8eca_12.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"has-drop-cap has-light-green-cyan-background-color has-background\">\u7e3d\u7d50\u800c\u8a00\uff0c\u5ee3\u5dde\u5357\u7ad9\u96d6\u662f\u540c\u6a23\u4eba\u591a\u64e0\u8feb\uff0c\u4f46\u8f49\u8eca\u9ad4\u9a57\u826f\u597d\u3002\u5982\u6df1\u5733\u5317\u767c\u8eca\u6642\u9593\u4e0d\u7406\u60f3\u7684\u8a71\uff0c\u5ee3\u5dde\u5357\u7ad9\u6bcb\u7591\u662f\u53e6\u4e00\u500b\u597d\u7684\u9078\u64c7\u3002<\/p>\n<p>Views: 110<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5e78\u800c\u4e0b\u8eca\u5f8c\u6709\u6e05\u6670\u660e\u78ba\u7684\u6307\u793a\uff0c\u6cbf\u6a13\u68af\uff08\u6216\u6276\u624b\u96fb\u68af\uff09\u76f4\u4e0a\u4e0d\u75283\u5206\u9418\uff0c\u4fbf\u5230\u9054\u5019\u8eca\u5927\u5802\uff0c\u6bcb\u9808\u518d\u63a5\u53d7\u5b89\u6aa2\u3002<\/p>\n","protected":false},"author":1,"featured_media":12902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,8],"tags":[],"class_list":["post-12898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2019_50-travelling","category-50-travelling"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/12898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=12898"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/12898\/revisions"}],"predecessor-version":[{"id":12911,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/12898\/revisions\/12911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/12902"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=12898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=12898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=12898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}