{"id":24640,"date":"2023-07-04T14:40:52","date_gmt":"2023-07-04T06:40:52","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=24640"},"modified":"2023-07-04T17:00:25","modified_gmt":"2023-07-04T09:00:25","slug":"20230625_50%e6%96%b0%e9%a6%ac%e8%a1%8c%e7%ac%ac%e4%ba%8c%e5%a4%a9%e4%b9%8bsheng-siong%e8%b6%85%e5%b8%82","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2023%e5%b9%b4\/24640\/","title":{"rendered":"20230625_50+\u65b0\u99ac\u884c\u7b2c\u4e8c\u5929\u4e4b\u6607\u677e(Sheng Siong)\u8d85\u5e02"},"content":{"rendered":"\n<p class=\"has-white-color has-vivid-purple-background-color has-text-color has-background\">\u5c0f\u5370\u5ea6\u534a\u65e5\u884c\u7d50\u675f\uff0c\u770b\u7740\u6642\u9593\u5c1a\u65e9\uff0c\u6bcb\u9808\u6025\u65bc\u8fa6\u7406\u9000\u623f\u624b\u7e8c\uff0c\u5728\u8fd4\u56de\u9152\u5e97\u9014\u4e2d\uff0c\u7d93\u904e\u6607\u677e(Sheng Siong)\u8d85\u5e02\uff0c\u9042\u9032\u5167\u770b\u770b\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24741\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_01-1024x768.jpg\" alt=\"\" class=\"wp-image-24741\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24742\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_02-1024x768.jpg\" alt=\"\" class=\"wp-image-24742\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24743\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_03-1024x768.jpg\" alt=\"\" class=\"wp-image-24743\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24744\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_04-1024x768.jpg\" alt=\"\" class=\"wp-image-24744\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24745\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_05-1024x768.jpg\" alt=\"\" class=\"wp-image-24745\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-white-color has-vivid-purple-background-color has-text-color has-background\">Sheng Siong\u8d85\u5e02\u8207\u9999\u6e2f\u7684\u4e00\u822c\u8d85\u5e02\u6c92\u6709\u5206\u5225\uff0c\u9577\u5f62\u7684\u8ca8\u67b6\u64fa\u6eff\u4e0d\u540c\u8ca8\u54c1\u4f9b\u9867\u5ba2\u9078\u8cfc\uff0c\u4e5f\u6709\u51cd\u8089\u6ac3\u548c\u51b7\u85cf\u6ac3\u51fa\u552e\u51b0\u51cd\u98df\u7269\uff0c\u800c\u901f\u92b7\u6216\u7279\u60e0\u8ca8\u54c1\u5247\u7f6e\u65bc\u4e3b\u8981\u901a\u9053\u65c1\uff0c\u6709\u52a9\u5438\u5f15\u9867\u5ba2\u7684\u76ee\u5149\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24746\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_06-1024x768.jpg\" alt=\"\" class=\"wp-image-24746\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_06-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_06-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_06-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_06.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24747\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_07-1024x768.jpg\" alt=\"\" class=\"wp-image-24747\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_07-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_07-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_07-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_07.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24748\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_08-1024x768.jpg\" alt=\"\" class=\"wp-image-24748\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_08-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_08-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_08-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_08.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24749\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_09-1024x768.jpg\" alt=\"\" class=\"wp-image-24749\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_09-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_09-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_09-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_09.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24750\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_10-1024x768.jpg\" alt=\"\" class=\"wp-image-24750\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_10-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_10-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_10-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_10.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-white-color has-vivid-purple-background-color has-text-color has-background\">\u552e\u50f9\u65b9\u9762\uff0c\u96d6\u6c92\u6709\u5168\u9762\u6838\u5c0d\uff0c\u4f46\u76f8\u5c0d\u9999\u6e2f\u8d85\u5e02\u7684\u8ca8\u54c1\u611f\u89ba\u4e0a\u8f03\u8cb4\uff0c\u5176\u4e2d\u4ee5\u51b0\u51cd\u5927\u8766\u70ba\u4f8b\uff0c1KG\u50f9\u9322\u70baSD 16.99\u5143\uff0c\u800c\u9999\u6e2f\u7d0480-90\u6e2f\u5143\u5de6\u53f3\uff0c\u9ad8\u51fa\u7d0420%\uff1b\u65b0\u9bae\u9ed1\u76ee\u9c78\uff0c1KG\u50f9\u9322\u70baSD 8.99\u5143\uff0c\u800c\u9999\u6e2f\u7d0440\u6e2f\u5143\u4fbf\u8cb7\u5f97\u4e00\u689d\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24751\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_11-1024x768.jpg\" alt=\"\" class=\"wp-image-24751\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24752\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_12-1024x768.jpg\" alt=\"\" class=\"wp-image-24752\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24754\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_13-1024x768.jpg\" alt=\"\" class=\"wp-image-24754\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24755\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_14-1024x768.jpg\" alt=\"\" class=\"wp-image-24755\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_14-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_14-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_14-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_14.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24756\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_15-1024x768.jpg\" alt=\"\" class=\"wp-image-24756\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_15-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_15-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_15-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230625_Sheng-Siong\u8d85\u5e02_15.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<p>Views: 109<\/p>","protected":false},"excerpt":{"rendered":"<p>\u552e\u50f9\u65b9\u9762\uff0c\u96d6\u6c92\u6709\u5168\u9762\u6838\u5c0d\uff0c\u4f46\u76f8\u5c0d\u9999\u6e2f\u8d85\u5e02\u7684\u8ca8\u54c1\u611f\u89ba\u4e0a\u8f03\u8cb4<\/p>\n","protected":false},"author":1,"featured_media":24744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[99,97],"tags":[],"class_list":["post-24640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2023_","category-97"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/24640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=24640"}],"version-history":[{"count":4,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/24640\/revisions"}],"predecessor-version":[{"id":24808,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/24640\/revisions\/24808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/24744"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=24640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=24640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=24640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}