{"id":26239,"date":"2023-07-25T21:42:49","date_gmt":"2023-07-25T13:42:49","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=26239"},"modified":"2023-07-26T15:46:59","modified_gmt":"2023-07-26T07:46:59","slug":"20230701_%e6%96%b0%e9%a6%ac%e8%a1%8c%e7%ac%ac%e5%85%ab%e5%a4%a9%e4%b9%8b%e6%a8%9f%e5%ae%9c%e6%a9%9f%e5%a0%b4%e7%be%8e%e9%a3%9f%e5%9d%8a","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2023%e5%b9%b4\/26239\/","title":{"rendered":"20230701_\u65b0\u99ac\u884c\u7b2c\u516b\u5929\u4e4b\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a"},"content":{"rendered":"\n<p class=\"has-luminous-vivid-orange-background-color has-background\">\u5728\u96e2\u958b\u661f\u8000\u6a1f\u5b9c\uff0c\u751a\u81f3\u53ef\u8aaa\u662f\u544a\u5225\u65b0\u52a0\u5761\u524d\uff0c\u4f86\u5230\u5730\u5eab\u4e8c\u5c64\u7684\u7f8e\u98df\u574a\uff0c\u9032\u98df\u9019\u8d9f\u884c\u7a0b\u4e2d\u5728\u65b0\u52a0\u5761\u7684\u6700\u5f8c\u665a\u9910\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26240\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_01-1024x768.jpg\" alt=\"\" class=\"wp-image-26240\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26241\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_02-1024x768.jpg\" alt=\"\" class=\"wp-image-26241\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26242\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_03-1024x768.jpg\" alt=\"\" class=\"wp-image-26242\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26243\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_04-1024x768.jpg\" alt=\"\" class=\"wp-image-26243\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26244\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_05-1024x768.jpg\" alt=\"\" class=\"wp-image-26244\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-luminous-vivid-orange-background-color has-background\">\u6a1f\u5b9c\u6a5f\u5834\u5167\u7684\u661f\u8000\u6a1f\u5b9c\u4e0d\u55ae\u662f\u4e00\u500b\u5341\u5206\u5b8c\u5584\u7684\u8cfc\u7269\u5546\u5834\uff0c\u540d\u5e97\u6797\u7acb\uff0c\u4e16\u754c\u7f8e\u98df\u5404\u5f0f\u5176\u5f0f\uff0c\u61c9\u6709\u76e1\u6709\uff0c\u4f46\u6536\u8cbb\u4e0d\u83f2\u3002\u5e78\u800c\u9019\u88cf\u8a2d\u6709\u6536\u8cbb\u8f03\u4fbf\u5b9c\u7684\u7f8e\u98df\u574a\uff0c\u66f4\u4e0d\u662f\u4e00\u500b\u5c0f\u5c0f\u7684\u7a7a\u9593\uff0c\u800c\u662f\u4f54\u5730\u751a\u5ee3\uff0c\u74b0\u5883\u8212\u9069\uff0c\u6709\u6578\u4ee5\u5341\u9593\u7684\u5c0f\u5e97\uff0c\u8b93\u904a\u5ba2\u6309\u5404\u81ea\u559c\u597d\u800c\u6709\u6240\u9078\u64c7\u3002\u55ae\u662f\u9019\u9ede\uff0c\u9999\u6e2f\u570b\u969b\u6a5f\u5834\u4fbf\u96e3\u4ee5\u76f8\u6bd4\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26245\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_06-1024x768.jpg\" alt=\"\" class=\"wp-image-26245\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_06-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_06-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_06-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_06.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26246\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_07-1024x768.jpg\" alt=\"\" class=\"wp-image-26246\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_07-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_07-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_07-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_07.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26247\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_08-1024x768.jpg\" alt=\"\" class=\"wp-image-26247\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_08-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_08-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_08-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_08.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26248\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_09-1024x768.jpg\" alt=\"\" class=\"wp-image-26248\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_09-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_09-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_09-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_09.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26249\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_10-1024x768.jpg\" alt=\"\" class=\"wp-image-26249\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_10-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_10-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_10-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_10.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-luminous-vivid-orange-background-color has-background\">\u6700\u5f8c\u9078\u64c7\u4e86\u7f8e\u98df\u574a\u6700\u6df1\u8655\u7684\u6d77\u5357\u96de\u98ef\uff0c\u5206\u5225\u9ede\u4e86\u4e00\u4eba\u4efd\uff0c\u6709\u83dc\u548c\u6e6f\u7684\u6d77\u5357\u96de\u98ef\u5957\u9910(SD 8.9\u5143)\uff0c\u4ee5\u53ca\u4e00\u5ba2\u5496\u55b1\u96de\u9eb5(SD 6.9\u5143)\uff0c\u5473\u9053\u4e0d\u932f\uff0c\u6027\u50f9\u6bd4\u9ad8\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26250\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_11-1024x768.jpg\" alt=\"\" class=\"wp-image-26250\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26251\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_12-1024x768.jpg\" alt=\"\" class=\"wp-image-26251\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26252\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_13-1024x768.jpg\" alt=\"\" class=\"wp-image-26252\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26253\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_14-1024x768.jpg\" alt=\"\" class=\"wp-image-26253\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_14-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_14-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_14-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_14.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"26254\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_15-1024x768.jpg\" alt=\"\" class=\"wp-image-26254\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_15-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_15-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_15-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230629_\u6a1f\u5b9c\u6a5f\u5834\u7f8e\u98df\u574a_15.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<p>Views: 56<\/p>","protected":false},"excerpt":{"rendered":"<p>\u9ede\u4e86\u4e00\u4eba\u4efd\uff0c\u6709\u83dc\u548c\u6e6f\u7684\u6d77\u5357\u96de\u98ef\u5957\u9910(SD 8.9\u5143)\uff0c\u4ee5\u53ca\u4e00\u5ba2\u5496\u55b1\u96de\u9eb5(SD 6.9\u5143)\uff0c\u5473\u9053\u4e0d\u932f\uff0c\u6027\u50f9\u6bd4\u9ad8\u3002<\/p>\n","protected":false},"author":1,"featured_media":26250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[99,97],"tags":[],"class_list":["post-26239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2023_","category-97"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/26239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=26239"}],"version-history":[{"count":2,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/26239\/revisions"}],"predecessor-version":[{"id":26278,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/26239\/revisions\/26278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/26250"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=26239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=26239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=26239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}