{"id":28888,"date":"2023-09-24T23:35:07","date_gmt":"2023-09-24T15:35:07","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=28888"},"modified":"2023-09-25T16:58:33","modified_gmt":"2023-09-25T08:58:33","slug":"20230922_50%e5%bb%a3%e5%b7%9e%e8%a1%8c%e7%ac%ac%e4%b8%80%e5%a4%a9%e4%b9%8b%e7%86%8a%e9%9c%b8%e6%b8%af%e5%bc%8f%e5%b0%8f%e9%a3%9f","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2023%e5%b9%b4\/28888\/","title":{"rendered":"20230922_50+\u5ee3\u5dde\u884c\u7b2c\u4e00\u5929\u4e4b\u718a\u9738\u6e2f\u5f0f\u5c0f\u98df"},"content":{"rendered":"\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background\">\u4f86\u5230\u6c38\u6176\u574a\u5df2\u662f\u665a\u4e0a1830\u6642\u4e86\uff0c\u7531\u4e0b\u8eca\u5f8c\u81f3\u4eca\u5df2\u6709\u8d85\u904e2\u842c\u6b65\u6578\uff0c\u7b26\u5408\u57ce\u5e02Citywalker\uff0c\u4e26\u975e\u4eab\u53d7\u751f\u6d3b\uff0c\u800c\u662f\u767c\u6398\u500b\u4eba\u559c\u597d\uff0c\u5145\u5be6\u4eba\u751f\u7684\u76ee\u7684\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28889\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_01-1024x768.jpg\" alt=\"\" class=\"wp-image-28889\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28890\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_02-768x1024.jpg\" alt=\"\" class=\"wp-image-28890\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_02-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_02-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_02.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28891\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_03-768x1024.jpg\" alt=\"\" class=\"wp-image-28891\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_03-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_03-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_03.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28892\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_04-1024x768.jpg\" alt=\"\" class=\"wp-image-28892\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28893\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_05-768x1024.jpg\" alt=\"\" class=\"wp-image-28893\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_05-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_05-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_05.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background\">\u5728\u574a\u5167\u7684\u7a7f\u8857\u904e\u5df7\uff0c\u9014\u7d93\u718a\u9738\u6e2f\u5f0f\u5c0f\u98df\uff0c\u672a\u6709\u53d7\u5230\u6d77\u5831\u4e0a\u662f\u5341\u5206\u719f\u6089\u7684\u96de\u86cb\u4ed4\u3001\u5496\u55b1\u9b5a\u86cb\u7b49\u9999\u6e2f\u5730\u9053\u5c0f\u5403\u5438\u5f15\uff0c\u53cd\u800c\u65c1\u908a\u590f\u65e5\u51b0\u723d\u50f9\u7684\u6731\u53e4\u529b\u51b0\u6c99\u537b\u96e3\u4ee5\u6297\u62d2\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28894\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_07-768x1024.jpg\" alt=\"\" class=\"wp-image-28894\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_07-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_07-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_07.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28895\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_06-768x1024.jpg\" alt=\"\" class=\"wp-image-28895\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_06-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_06-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_06.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28896\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_08-1024x768.jpg\" alt=\"\" class=\"wp-image-28896\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_08-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_08-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_08-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_08.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28897\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_09-1024x768.jpg\" alt=\"\" class=\"wp-image-28897\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_09-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_09-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_09-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_09.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28898\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_10-768x1024.jpg\" alt=\"\" class=\"wp-image-28898\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_10-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_10-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_10.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background\">\u9032\u5e97\u8cfc\u8cb7\u4e862\u676f\uff0c\u51b0\u6c99\u96d6\u975e\u7dbf\u51b0\uff0c\u4f46\u6253\u5f97\u751a\u70ba\u7d30\u7dfb\uff0c\u52a0\u4e0a\u5341\u5206\u6fc3\u90c1\u7684\u6731\u53e4\u529b\u5473\u9053\uff0c\u8f03\u4e0d\u5c11\u51b0\u6c99\u5e97\uff0c\u5c24\u5176\u662f\u4fbf\u5229\u5e97\u92b7\u552e\u300c\u5927\u7c92\u88dd\u51b0\u6c99\u300d\u7684\u597d\u5473\u5f97\u591a\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"28899\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_11-768x1024.jpg\" alt=\"\" class=\"wp-image-28899\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_11-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_11-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_11.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28900\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_12-1024x768.jpg\" alt=\"\" class=\"wp-image-28900\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28901\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_13-1024x768.jpg\" alt=\"\" class=\"wp-image-28901\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28902\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_14-1024x768.jpg\" alt=\"\" class=\"wp-image-28902\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_14-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_14-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_14-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_14.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"28903\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_15-1024x768.jpg\" alt=\"\" class=\"wp-image-28903\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_15-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_15-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_15-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20230922_\u718a\u9738\u6c99\u51b0_15.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<p>Views: 111<\/p>","protected":false},"excerpt":{"rendered":"<p>\u51b0\u6c99\u96d6\u975e\u7dbf\u51b0\uff0c\u4f46\u6253\u5f97\u751a\u70ba\u7d30\u7dfb\uff0c\u52a0\u4e0a\u5341\u5206\u6fc3\u90c1\u7684\u6731\u53e4\u529b\u5473\u9053\uff0c\u8f03\u4e0d\u5c11\u51b0\u6c99\u5e97\u597d\u5473\u5f97\u591a\u3002<\/p>\n","protected":false},"author":1,"featured_media":28895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[99,97],"tags":[],"class_list":["post-28888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2023_","category-97"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/28888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=28888"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/28888\/revisions"}],"predecessor-version":[{"id":28904,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/28888\/revisions\/28904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/28895"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=28888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=28888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=28888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}