{"id":32253,"date":"2023-11-25T01:08:07","date_gmt":"2023-11-24T17:08:07","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=32253"},"modified":"2024-03-14T12:16:24","modified_gmt":"2024-03-14T04:16:24","slug":"%e9%a6%99%e6%b8%af%e5%8d%81%e5%85%ab%e5%8d%80%e5%b0%8e%e8%b3%9e%e4%b9%8b%e6%b8%af%e5%b3%b6%e5%8d%97%e5%8d%80","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/%e9%a6%99%e6%b8%af%e5%8d%81%e5%85%ab%e5%8d%80%e5%b0%8e%e8%b3%9e\/%e6%b8%af%e5%b3%b6%e5%8d%80%e5%b0%8e%e8%b3%9e\/%e5%8d%97%e5%8d%80%e5%b0%8e%e8%b3%9e\/32253\/","title":{"rendered":"\u9999\u6e2f\u5341\u516b\u5340\u5c0e\u8cde\u4e4b\u6e2f\u5cf6\u5357\u5340"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>20240226_50+\u9999\u6e2f\u5c0e\u8cde\u884c\u4e4b\u592a\u5e73\u5c71\u9023\u7d50(\u5c71\u9802\u5ee3\u5834_\u67ef\u58eb\u7538\u5c71\u904a\u6a02\u5834_\u820a\u7e3d\u7763\u5c71\u9802\u5225\u5885\u5b88\u885b\u5ba4_\u5c71\u9802\u82b1\u5712_\u897f\u9ad8\u5c71_\u677e\u6797\u5ee2\u5821)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"CeGpAXFrIO\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/37097\/\">20240226_50+\u9999\u6e2f\u5c0e\u8cde\u884c\u4e4b\u592a\u5e73\u5c71\u9023\u7d50(\u5c71\u9802\u5ee3\u5834_\u67ef\u58eb\u7538\u5c71\u904a\u6a02\u5834_\u820a\u7e3d\u7763\u5c71\u9802\u5225\u5885\u5b88\u885b\u5ba4_\u5c71\u9802\u82b1\u5712_\u897f\u9ad8\u5c71_\u677e\u6797\u5ee2\u5821)<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c20240226_50+\u9999\u6e2f\u5c0e\u8cde\u884c\u4e4b\u592a\u5e73\u5c71\u9023\u7d50(\u5c71\u9802\u5ee3\u5834_\u67ef\u58eb\u7538\u5c71\u904a\u6a02\u5834_\u820a\u7e3d\u7763\u5c71\u9802\u5225\u5885\u5b88\u885b\u5ba4_\u5c71\u9802\u82b1\u5712_\u897f\u9ad8\u5c71_\u677e\u6797\u5ee2\u5821)\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/37097\/embed\/#?secret=RWqVLMjQXA#?secret=CeGpAXFrIO\" data-secret=\"CeGpAXFrIO\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>20231202_50+\u9999\u6e2f\u4ed4\u5c0e\u8cde\u884c\u9023\u7d50(\u9d28\u8137\u6d32\u6d2a\u8056\u53e4\u5edf_\u98a8\u4e4b\u5854\u516c\u5712_\u6c34\u6708\u5bae_\u9999\u6e2f\u4ed4\u8857\u6e21_\u5929\u540e\u53e4\u5edf_\u820a\u9999\u6e2f\u4ed4\u8b66\u7f72_\u9ec3\u7af9\u5751\u65b0\u570d\u675110\u865f\u5c4b_\u9ec3\u7af9\u5751\u77f3\u523b)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"wrg6V42fkx\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2023%e5%b9%b4\/33306\/\">20231202_50+\u9999\u6e2f\u4ed4\u5c0e\u8cde\u884c\u9023\u7d50(\u9d28\u8137\u6d32\u6d2a\u8056\u53e4\u5edf_\u98a8\u4e4b\u5854\u516c\u5712_\u6c34\u6708\u5bae_\u9999\u6e2f\u4ed4\u8857\u6e21_\u5929\u540e\u53e4\u5edf_\u820a\u9999\u6e2f\u4ed4\u8b66\u7f72_\u9ec3\u7af9\u5751\u65b0\u570d\u675110\u865f\u5c4b_\u9ec3\u7af9\u5751\u77f3\u523b)<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c20231202_50+\u9999\u6e2f\u4ed4\u5c0e\u8cde\u884c\u9023\u7d50(\u9d28\u8137\u6d32\u6d2a\u8056\u53e4\u5edf_\u98a8\u4e4b\u5854\u516c\u5712_\u6c34\u6708\u5bae_\u9999\u6e2f\u4ed4\u8857\u6e21_\u5929\u540e\u53e4\u5edf_\u820a\u9999\u6e2f\u4ed4\u8b66\u7f72_\u9ec3\u7af9\u5751\u65b0\u570d\u675110\u865f\u5c4b_\u9ec3\u7af9\u5751\u77f3\u523b)\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2023%e5%b9%b4\/33306\/embed\/#?secret=O9deqGHYwV#?secret=wrg6V42fkx\" data-secret=\"wrg6V42fkx\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p>Views: 58<\/p>","protected":false},"excerpt":{"rendered":"<p>\u9999\u6e2f\u5341\u516b\u5340\u5c0e\u8cde\u4e4b\u6e2f\u5cf6\u5357\u5340<\/p>\n","protected":false},"author":1,"featured_media":11226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-32253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-109"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/32253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=32253"}],"version-history":[{"count":5,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/32253\/revisions"}],"predecessor-version":[{"id":38034,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/32253\/revisions\/38034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/11226"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=32253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=32253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=32253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}