{"id":45413,"date":"2024-07-05T20:57:22","date_gmt":"2024-07-05T12:57:22","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=45413"},"modified":"2024-07-05T20:57:24","modified_gmt":"2024-07-05T12:57:24","slug":"20240622_50%e9%ab%98%e9%9b%84%e6%be%8e%e6%b9%96%e8%a1%8c%e7%ac%ac%e5%9b%9b%e5%a4%a9%e4%b9%8b%e8%8a%b1%e5%aa%bd%e5%a4%a7%e8%85%b8%e9%a6%99%e8%85%b8%e5%8d%88%e9%a4%90","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/45413\/","title":{"rendered":"20240622_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u56db\u5929\u4e4b\u82b1\u5abd\u5927\u8178\u9999\u8178\u5348\u9910"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u7d93\u904e\u6628\u5929\u6574\u65e5\u884c\u7a0b\uff0c\u4eca\u65e9\u6c7a\u5b9a\u7559\u5728\u623f\u9593\u770b\u770b\u624b\u6a5f\uff0c\u5beb\u5beb\u6587\u7a3f\uff0c\u9042\u5728\u5bcc\u6797\u6f22\u5821\u9032\u98df\u86cb\u9905\u5f8c\u4fbf\u6377\u8fd4\u6c11\u5bbf\uff0c\u5f85\u81f3\u4e0b\u53481330\u6642\u96e2\u958b\uff0c\u5f80\u5916\u627e\u5403\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45414\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_01-1024x768.jpg\" alt=\"\" class=\"wp-image-45414\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45415\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_02-1024x768.jpg\" alt=\"\" class=\"wp-image-45415\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45416\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_03-1024x768.jpg\" alt=\"\" class=\"wp-image-45416\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u6c11\u5bbf\u5c0d\u51fa\u7684\u5927\u8def\uff0c\u53f3\u8f49\u53ef\u524d\u5f80\u5bcc\u6797\u6f22\u5821\u65e9\u9910\u5e97\uff0c\u4f46\u6b64\u6642\u5df2\u95dc\u9580\uff0c\u800c\u5de6\u8d70\u81f3\u5206\u53c9\u8def\u53e3\u5247\u67097-11\u548c\u5168\u5bb6\u4fbf\u5229\u5e97\uff0c\u4ee5\u53ca\u6578\u9593\u5c0f\u5403\u5e97\u3002\u5176\u4e2d\u6d2a\u5bb6\u70b8\u7cbf\u9580\u524d\u6709\u4e0d\u5c11\u5e74\u9752\u4eba\u6392\u968a\u8cb7\u9910\uff0c\u4f46\u70b8\u7269\u4f5c\u70ba\u5348\u9910\u4e26\u975e\u500b\u4eba\u559c\u597d\uff0c\u6545\u5230\u5c0d\u9762\u7684\u82b1\u5abd\u5927\u8178\u9999\u8178\u9032\u98df\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45424\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_11-1024x768.jpg\" alt=\"\" class=\"wp-image-45424\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45417\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_04-1024x768.jpg\" alt=\"\" class=\"wp-image-45417\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45418\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_05-1024x768.jpg\" alt=\"\" class=\"wp-image-45418\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u82b1\u5abd\u5927\u8178\u9999\u8178\u662f\u4e00\u9593\u4ee5\u95dc\u6771\u716e\u70ba\u4e3b\u98df\u7684\u5e97\u5bb6\uff0c\u5e97\u9762\u4e0d\u5927\uff0c\u6709\u6578\u5f35\u67b1\u6905\uff0c\u98df\u5ba2\u4ee5\u9a0e\u8eca\u8005\u6216\u5916\u5e36\u70ba\u4e3b\u3002\u5206\u5225\u9ede\u4e86\u4e00\u7897\u6ef7\u5927\u8178\u8089\u71e5\u98ef(55\u5143)\u548c\u8c6c\u96dc\u51ac\u7c89(70\u5143)\uff0c\u4e26\u5728\u95dc\u6771\u716e\u71b1\u76e4\u4e2d\uff0c\u62ff\u53d6\u5c0f\u8ca2\u4e38(15\u51434\u9846)\u3001\u9ec3\u91d1\u4e38(20\u51433\u9846)\u3001\u82b1\u679d\u4e38(45\u5143)\u548c\u82e6\u74dc\u5c01\u8089(40\u5143)\u7b49\u4ea4\u7d66\u5e97\u5bb6\u8655\u7406\uff0c\u5473\u9053\u4f73\uff0c\u6709\u53e3\u611f\uff0c\u5176\u4e2d\u9644\u6709\u6ef7\u5927\u8178\u7684\u8089\u71e5\u98ef\uff0c\u4e0d\u55ae\u8f03\u524d\u665a\u89c0\u97f3\u4ead\u7684\u300c\u6d77\u9678\u9eb5\u300d\u5c0f\u5e97\u7684\u6240\u8b02\u5927\u7897\u9e75\u8089\u98ef\u597d\u5403\u5f97\u591a\uff0c\u4efd\u91cf\u4ea6\u5927\u5f97\u591a\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45419\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_06-1024x768.jpg\" alt=\"\" class=\"wp-image-45419\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_06-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_06-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_06-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_06.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45420\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_07-1024x768.jpg\" alt=\"\" class=\"wp-image-45420\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_07-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_07-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_07-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_07.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45421\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_08-1024x768.jpg\" alt=\"\" class=\"wp-image-45421\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_08-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_08-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_08-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_08.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45422\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_09-1024x768.jpg\" alt=\"\" class=\"wp-image-45422\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_09-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_09-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_09-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_09.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45423\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_10-1024x768.jpg\" alt=\"\" class=\"wp-image-45423\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_10-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_10-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_10-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240622_\u82b1\u5abd\u5927\u8178\u9999\u8178_10.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u4eca\u6614\u6587\u7ae0\uff1a<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u300c\u6d77\u9678\u9eb5\u300d\u665a\u9910<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"MSRjZhDHxa\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/45011\/\">20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u300c\u6d77\u9678\u9eb5\u300d\u665a\u9910<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u300c\u6d77\u9678\u9eb5\u300d\u665a\u9910\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/45011\/embed\/#?secret=eUwXHB5vUZ#?secret=MSRjZhDHxa\" data-secret=\"MSRjZhDHxa\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p>Views: 48<\/p>","protected":false},"excerpt":{"rendered":"<p>\u9644\u6709\u6ef7\u5927\u8178\u7684\u8089\u71e5\u98ef\uff0c\u4e0d\u55ae\u597d\u5403\uff0c\u4efd\u91cf\u4ea6\u591a<\/p>\n","protected":false},"author":1,"featured_media":45420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[130,128],"tags":[],"class_list":["post-45413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024_","category-128"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/45413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=45413"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/45413\/revisions"}],"predecessor-version":[{"id":45425,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/45413\/revisions\/45425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/45420"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=45413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=45413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=45413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}