{"id":45595,"date":"2024-07-08T21:40:26","date_gmt":"2024-07-08T13:40:26","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=45595"},"modified":"2024-07-08T21:40:27","modified_gmt":"2024-07-08T13:40:27","slug":"20240623_50%e9%ab%98%e9%9b%84%e6%be%8e%e6%b9%96%e8%a1%8c%e7%ac%ac%e4%ba%94%e5%a4%a9%e4%b9%8b%e6%be%8e%e6%b9%96%e9%a6%ac%e5%85%ac%e6%a9%9f%e5%a0%b4","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/45595\/","title":{"rendered":"20240623_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e94\u5929\u4e4b\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u4eca\u65e9\u662f\u6f8e\u6e56\u6700\u5f8c\u4e00\u5929\uff0c\u672a\u6709\u5982\u524d\u5169\u5929\u5728\u5bcc\u6797\u6f22\u5821\u5167\u7528\u65e9\u9910\uff0c\u800c\u662f\u8cb7\u4e86\u5169\u500b\u7f8e\u5473\u7684\u8766\u5821(55\u5143)\uff0c\u56de\u6c11\u5bbf\u623f\u9593\u7684\u7a7a\u8abf\u74b0\u5883\u4e0b\uff0c\u518d\u8abf\u4e00\u676f\u4e09\u5408\u4e00\u71b1\u5496\u5561\uff0c\u5750\u5728\u4e00\u5f35\u5c0f\u684c\u4e0a\u7528\u9910\uff0c\u611f\u89ba\u66f4\u4f73\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45596\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_01-1024x768.jpg\" alt=\"\" class=\"wp-image-45596\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45597\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_02-1024x768.jpg\" alt=\"\" class=\"wp-image-45597\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45598\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_03-1024x768.jpg\" alt=\"\" class=\"wp-image-45598\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45599\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_04-1024x768.jpg\" alt=\"\" class=\"wp-image-45599\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45600\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_05-1024x768.jpg\" alt=\"\" class=\"wp-image-45600\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u4e0a\u53480840\u6642\u9000\u623f\uff0c0900\u6642\u9a0e\u8eca\u56de\u5230\u842c\u921e\u8eca\u884c\uff0c\u96a8\u5373\u5c07\u6a5f\u8eca\u6b78\u9084\u3002\u6216\u8a31\u7531\u65bc\u6709\u591a\u6279\u79df\u8eca\u65c5\u8005\u5148\u5f8c\u5230\u4f86\uff0c\u5f85\u81f30910\u6642\uff0c\u8eca\u884c\u624d\u5b89\u6392\u514d\u8cbb\u5c08\u8eca\u9001\u5f80\u99ac\u516c\u6a5f\u5834\uff0c\u8eca\u7a0b\u53ea\u970010\u5206\u9418\uff0c\u540c\u6642\u4ea6\u6709\u53e6\u4e00\u7d44\u79df\u8eca\u5ba2\u767b\u8eca\uff0c\u53ef\u898b\u8eca\u884c\u4eba\u54e1\u5341\u5206\u5fd9\u788c\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45601\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_06-1024x768.jpg\" alt=\"\" class=\"wp-image-45601\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_06-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_06-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_06-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_06.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45602\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_07-1024x768.jpg\" alt=\"\" class=\"wp-image-45602\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_07-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_07-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_07-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_07.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45603\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_08-1024x768.jpg\" alt=\"\" class=\"wp-image-45603\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_08-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_08-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_08-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_08.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45604\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_09-1024x768.jpg\" alt=\"\" class=\"wp-image-45604\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_09-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_09-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_09-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_09.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45605\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_10-1024x768.jpg\" alt=\"\" class=\"wp-image-45605\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_10-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_10-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_10-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_10.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u56db\u5929\u524d\u7531\u9ad8\u96c4\u4e58\u6f8e\u6e56\u8f2a\u5230\u99ac\u516c\u5357\u6d77\u78bc\u982d\uff0c\u4eca\u65e5\u96e2\u958b\u5247\u9078\u64c7\u7acb\u69ae\u822a\u7a7a\u7684\u7684\u822a\u73edB79106\uff0c\u5f80\u53f0\u5317\u677e\u5c71\u6a5f\u5834\u3002\u7531\u65bc\u662f\u5167\u9678\u822a\u73ed\uff0c\u822a\u7a7a\u516c\u53f8\u672a\u6709\u63d0\u4f9b\u7db2\u4e0a\u690d\u6a5f\u5b89\u6392\uff0c\u5e78\u800c\u524d\u67b1\u690d\u6a5f\u624b\u7e8c\u4ea6\u5341\u5206\u7c21\u55ae\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45606\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_11-1024x768.jpg\" alt=\"\" class=\"wp-image-45606\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45607\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_12-1024x768.jpg\" alt=\"\" class=\"wp-image-45607\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45608\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_13-1024x768.jpg\" alt=\"\" class=\"wp-image-45608\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45609\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_14-1024x768.jpg\" alt=\"\" class=\"wp-image-45609\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_14-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_14-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_14-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_14.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"45610\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_15-1024x768.jpg\" alt=\"\" class=\"wp-image-45610\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_15-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_15-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_15-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240623_\u6f8e\u6e56\u99ac\u516c\u6a5f\u5834_15.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u99ac\u516c\u822a\u5ec8\u6a13\u9ad8\u4e09\u5c64\uff0c\u8ca0\u4e00\u5c64\u70ba\u505c\u8eca\u5834\uff0c\u4e0a\u5c64\u70ba\u822a\u7a7a\u516c\u53f8\u6ac3\u53f0\u3001\u884c\u674e\u63d0\u9818\u5340\u3001\u8d85\u5546\u7b49\u3002\u5728\u6ac3\u4f4d\u5b8c\u6210\u624b\u7e8c\u5f8c\uff0c\u6a5f\u5834\u5927\u5802\u4e8c\u6a13\u6587\u5316\u85dd\u5eca\u6b63\u8209\u884c\u300c\u559a\u56de\u9752\u6625\u6cb9\u756b\u806f\u5c55\u300d\uff0c\u7a0d\u4f5c\u505c\u7559\u6b23\u8cde\u5f8c\uff0c\u518d\u7d93\u904e\u5b89\u6aa2\u5230\u5019\u6a5f\u5ba4\u3002\u7d04\u65bc1030\u6642\u767b\u6a5f\uff0c1100\u6642\u51fa\u767c\u671d\u53f0\u5317\u98db\u53bb\uff0c\u6a5f\u7a0b\u7d041\u5c0f\u6642\u3002<\/p>\n\n\n\n<p>\u4eca\u6614\u6587\u7ae0\uff1a<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u842c\u921e\u79df\u8eca<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"5fA55WOopE\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/44729\/\">20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u842c\u921e\u79df\u8eca<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u842c\u921e\u79df\u8eca\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/44729\/embed\/#?secret=vmzAXv9Dl9#?secret=5fA55WOopE\" data-secret=\"5fA55WOopE\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u6f8e\u6e56\u99ac\u516c\u5357\u6d77\u78bc\u982d<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-50-\u50b3\u627f wp-block-embed-50-\u50b3\u627f\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"lTefDJiZEg\"><a href=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/44621\/\">20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u6f8e\u6e56\u99ac\u516c\u5357\u6d77\u78bc\u982d<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u300c20240620_50+\u9ad8\u96c4\u6f8e\u6e56\u884c\u7b2c\u4e8c\u5929\u4e4b\u6f8e\u6e56\u99ac\u516c\u5357\u6d77\u78bc\u982d\u300d &#8212; 50+\u50b3\u627f\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/44621\/embed\/#?secret=KddBm8gTLy#?secret=lTefDJiZEg\" data-secret=\"lTefDJiZEg\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p>Views: 83<\/p>","protected":false},"excerpt":{"rendered":"<p>\u99ac\u516c\u822a\u5ec8\u6a13\u9ad8\u4e09\u5c64\uff0c\u8ca0\u4e00\u5c64\u70ba\u505c\u8eca\u5834\uff0c\u4e0a\u5c64\u70ba\u822a\u7a7a\u516c\u53f8\u6ac3\u53f0\u3001\u884c\u674e\u63d0\u9818\u5340\u3001\u8d85\u5546\u7b49<\/p>\n","protected":false},"author":1,"featured_media":45609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[130,128],"tags":[],"class_list":["post-45595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024_","category-128"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/45595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=45595"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/45595\/revisions"}],"predecessor-version":[{"id":45611,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/45595\/revisions\/45611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/45609"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=45595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=45595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=45595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}