{"id":47357,"date":"2024-08-06T22:23:27","date_gmt":"2024-08-06T14:23:27","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=47357"},"modified":"2024-08-06T22:23:28","modified_gmt":"2024-08-06T14:23:28","slug":"20240714_50%e9%a0%86%e5%be%b7%e8%a1%8c%e7%ac%ac%e4%b8%89%e5%a4%a9%e4%b9%8b%e9%be%8d%e5%b3%b0%e5%b1%b1%e6%a3%ae%e6%9e%97%e5%85%ac%e5%9c%92","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/47357\/","title":{"rendered":"20240714_50+\u9806\u5fb7\u884c\u7b2c\u4e09\u5929\u4e4b\u9f8d\u5cf0\u5c71\u68ee\u6797\u516c\u5712"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u4e0b\u5348\u8fd1\u516d\u6642\u96e2\u958b\u9152\u5e97\uff0c\u6cbf\u8c50\u83ef\u5357\u8def\u5f92\u6b65\u5357\u4e0b\uff0c\u82b1\u4e8620\u591a\u5206\u9418\u4f86\u5230\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712\u5165\u53e3\u5ee3\u5834\uff0c\u706b\u71b1\u7684\u967d\u5149\u4e5f\u63db\u4e0a\u4e86\u65b0\u88dd\uff0c\u4e00\u7e37\u91d1\u9ec3\u8272\u7684\u5915\u7167\u7051\u7247\u5927\u5730\uff0c\u5341\u5206\u8000\u76ee\uff0c\u9583\u4eae\u7684\u971e\u5149\u775c\u5f97\u773c\u775b\u4e5f\u5f35\u4e0d\u958b\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47358\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_01-1024x768.jpg\" alt=\"\" class=\"wp-image-47358\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47359\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_02-1024x768.jpg\" alt=\"\" class=\"wp-image-47359\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47360\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_03-1024x768.jpg\" alt=\"\" class=\"wp-image-47360\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47361\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_04-1024x768.jpg\" alt=\"\" class=\"wp-image-47361\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47362\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_05-1024x768.jpg\" alt=\"\" class=\"wp-image-47362\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u9f8d\u5cf0\u5c71\u68ee\u6797\u516c\u5712\u7dca\u9760\u6d77\u62d4\u5343\u591a\u7c73\u7684\u5929\u6e56\u68ee\u6797\u516c\u5712\u4e00\u5076\uff0c\u5c6c\u5927\u578b\u793e\u5340\u516c\u5712\uff0c\u9664\u8a2d\u6709\u5712\u6e56\u3001\u5404\u9805\u5eb7\u9ad4\u8a2d\u65bd\u3001\u6236\u5916\u904a\u6cf3\u6c60\uff0c\u751a\u81f3\u6a5f\u52d5\u904a\u6232\u5834\uff0c\u4f9b\u5e02\u6c11\u5927\u773e\u904b\u52d5\u6d88\u9592\u5916\uff0c\u9084\u6709\u7740\u6975\u70ba\u8c50\u5bcc\u7684\u5927\u81ea\u7136\u751f\u614b\u74b0\u5883\uff0c\u662f\u91ce\u751f\u52d5\u690d\u7269\u7684\u7406\u60f3\u68f2\u606f\u5730\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47363\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_06-1024x768.jpg\" alt=\"\" class=\"wp-image-47363\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_06-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_06-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_06-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_06.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47364\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_07-1024x768.jpg\" alt=\"\" class=\"wp-image-47364\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_07-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_07-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_07-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_07.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47365\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_08-1024x768.jpg\" alt=\"\" class=\"wp-image-47365\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_08-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_08-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_08-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_08.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47366\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_09-1024x768.jpg\" alt=\"\" class=\"wp-image-47366\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_09-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_09-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_09-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_09.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47367\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_10-1024x768.jpg\" alt=\"\" class=\"wp-image-47367\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_10-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_10-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_10-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_10.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u7531\u5ee3\u5834\u6771\u5357\u9580\u9032\u5712\uff0c\u4e00\u67f1\u64ce\u5929\u7684\u5de8\u578b\u7d05\u8272\u96d5\u5851\u8fce\u967d\u800c\u7acb\uff0c\u65e2\u6436\u773c\uff0c\u53c8\u58ef\u89c0\u3002\u524d\u884c\u4e0d\u9060\u662f\u4e00\u500b\u6d77\u6d0b\u4e16\u754c\u69cb\u601d\u7684\u5713\u5f62\u5ee3\u5834\uff0c\u591a\u689d\u9280\u8272\u6d77\u8c5a\u85dd\u8853\u88dd\u7f6e\u66a2\u6cf3\u5176\u4e2d\uff0c\u9817\u70ba\u6709\u8da3\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47368\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_11-1024x768.jpg\" alt=\"\" class=\"wp-image-47368\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47369\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_12-1024x768.jpg\" alt=\"\" class=\"wp-image-47369\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47370\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_13-1024x768.jpg\" alt=\"\" class=\"wp-image-47370\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47371\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_14-1024x768.jpg\" alt=\"\" class=\"wp-image-47371\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_14-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_14-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_14-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_14.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"47372\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_15-1024x768.jpg\" alt=\"\" class=\"wp-image-47372\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_15-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_15-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_15-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20240713_\u9806\u5fb7\u82b1\u5cf0\u5c71\u68ee\u6797\u516c\u5712_15.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-background-color has-background\">\u4f86\u5230\u516c\u5712\u4e2d\u5fc3\u4f4d\u7f6e\u662f\u591a\u500b\u85cd\u7403\u5834\uff0c\u6253\u7403\u5065\u5152\u63ee\u6c57\u5982\u96e8\uff0c\u73a9\u5f97\u4e0d\u5955\u6a02\u4e4e\u3002\u9019\u88cf\u7af6\u8cfd\u6b63\u9163\uff0c\u53f1\u559d\u7d1b\u50b3\uff0c\u53e6\u4e00\u7aef\u5712\u6e56\u5167\u5247\u662f\u8f15\u8f15\u7d30\u8a9e\uff0c\u6216\u5728\u8ac7\u5fc3\uff0c\u53c8\u6216\u53d6\u666f\u62cd\u7167\uff0c\u5404\u53d6\u6240\u9700\uff0c\u6a02\u4e5f\u878d\u878d\u3002<\/p>\n<p>Views: 100<\/p>","protected":false},"excerpt":{"rendered":"<p>\u4e00\u67f1\u64ce\u5929\u7684\u5de8\u578b\u7d05\u8272\u96d5\u5851\u8fce\u967d\u800c\u7acb\uff0c\u65e2\u6436\u773c\uff0c\u53c8\u58ef\u89c0\u3002<\/p>\n","protected":false},"author":1,"featured_media":47367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[130,128],"tags":[],"class_list":["post-47357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024_","category-128"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/47357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=47357"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/47357\/revisions"}],"predecessor-version":[{"id":47373,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/47357\/revisions\/47373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/47367"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=47357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=47357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=47357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}