{"id":52243,"date":"2024-11-18T21:12:22","date_gmt":"2024-11-18T13:12:22","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=52243"},"modified":"2024-11-19T17:15:32","modified_gmt":"2024-11-19T09:15:32","slug":"20241113_50%e5%b3%b4%e6%b8%af%e8%a1%8c%e7%ac%ac%e4%b8%80%e5%a4%a9%e4%b9%8b%e5%bb%a3%e8%82%87%e6%9c%83%e9%a4%a8","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/52243\/","title":{"rendered":"20241113_50+\u5cf4\u6e2f\u884c\u7b2c\u4e00\u5929\u4e4b\u5ee3\u8087\u6703\u9928"},"content":{"rendered":"\n<p class=\"has-luminous-vivid-orange-background-color has-background\">\u96e2\u958b\u6703\u5b89\u4ead\uff0c\u7e7c\u7e8c\u5728\u6703\u5b89\u53e4\u57ce\uff0c\u5916\u7246\u4ee5\u9ec3\u8272\u70ba\u4e3b\u7684\u820a\u6a13\u7fa4\u9593\u7a7f\u68ad\uff0c\u671f\u9593\u5728\u8def\u908a\u6524\u770b\u5230\u8d8a\u5357\u5c0f\u5403\uff0c\u9ec3\u8272\u9905\u76ae\u593e\u96dc\u9921\u6599\u7684\u300c\u70e4\u8766\u9905\u300d\uff0c\u5341\u5206\u4fbf\u5b9c\uff0c\u4fbf\u82b14K\u8cb7\u4f86\u4e00\u7247\u5690\u5690\u3002\u6216\u8a31\u6524\u8ca9\u7684\u300c\u78b3\u706b\u300d\u904e\u5c0f\uff0c\u53c8\u6216\u8766\u9905\u5df2\u300c\u9592\u7f6e\u300d\u4e86\u4e00\u6bb5\u6642\u9593\uff0c\u9905\u76ae\u5df2\u5931\u53bb\u9999\u8106\u53e3\u611f\uff0c\u53ea\u6709\u9921\u6599\u9084\u4fdd\u6301\u7f8e\u5473\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52244\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_01-1024x768.jpg\" alt=\"\" class=\"wp-image-52244\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52245\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_02-1024x768.jpg\" alt=\"\" class=\"wp-image-52245\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52247\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_04-1024x768.jpg\" alt=\"\" class=\"wp-image-52247\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52248\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_05-1024x768.jpg\" alt=\"\" class=\"wp-image-52248\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52249\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_06-1024x768.jpg\" alt=\"\" class=\"wp-image-52249\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_06-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_06-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_06-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_06.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-luminous-vivid-orange-background-color has-background\">\u5403\u904e\u8766\u9905\u5f8c\uff0c\u6cbf\u53e4\u57ce\u5c0f\u8857\u7a84\u5df7\u524d\u884c\uff0c\u4e0d\u77e5\u4e0d\u89ba\u4f86\u5230\u5c6c\u83ef\u4eba\u5efa\u7bc9\u5730\u6a19\u4e4b\u4e00\u7684\u5ee3\u8087\u6703\u9928\u3002\u6709\u5225\u65bc\u6703\u5b89\u4ead\u7684\u300c\u4e00\u822c\u300d\uff0c\u539f\u662f\u6614\u65e5\u5728\u8d8a\u5357\u5f9e\u4e8b\u8cbf\u6613\u751f\u610f\u7684\u4e2d\u570b\u5546\u4eba\u5275\u7acb\uff0c\u7528\u4f5c\u6d3d\u8ac7\u751f\u610f\u3001\u4ea4\u6d41\u7d93\u9a57\u5916\uff0c\u9084\u662f\u7948\u798f\u554f\u597d\u7684\u5edf\u5b87\u6240\u5728\u5730\u7684\u5ee3\u8087\u6703\u9928\uff0c\u88cf\u88cf\u5916\u5916\u90fd\u66f4\u70ba\u7cbe\u7f8e\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52246\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_03-1024x768.jpg\" alt=\"\" class=\"wp-image-52246\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52250\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_07-1024x768.jpg\" alt=\"\" class=\"wp-image-52250\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_07-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_07-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_07-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_07.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"52251\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_08-768x1024.jpg\" alt=\"\" class=\"wp-image-52251\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_08-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_08-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_08.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"52252\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_09-768x1024.jpg\" alt=\"\" class=\"wp-image-52252\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_09-768x1024.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_09-225x300.jpg 225w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_09.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52253\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_10-1024x768.jpg\" alt=\"\" class=\"wp-image-52253\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_10-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_10-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_10-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_10.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-luminous-vivid-orange-background-color has-background\">\u5728\u8d8a\u5357\u6703\u5b89\uff0c\u5982\u5ee3\u8087\u6703\u9928\u3001\u65e5\u672c\u6a4b\u7b49\u5927\u90e8\u5206\u666f\u9ede\u5747\u9700\u9580\u7968\u624d\u80fd\u9032\u5167\uff0c\u800c\u552e\u7968\u8655\u5206\u8a2d\u5404\u500b\u4e3b\u8981\u8def\u53e3\uff0c\u6bcf\u500b\u666f\u9ede\u9580\u7968120K\uff0c\u904a\u5ba2\u53ef\u4efb\u610f\u8cfc\u8cb7\u3002\u4f46\u7531\u65bc\u5728\u9580\u5916\u6240\u898b\uff0c\u5ee3\u8087\u6703\u9928\u7684\u9580\u724c\u574a\u3001\u706b\u5f62\u7684\u5c71\u7246\uff0c\u4ee5\u53ca\u6b63\u810a\u4e0a\u7684\u300c\u96d9\u9f8d\u722d\u73e0\u300d\u9676\u98fe\uff0c\u8207\u9999\u6e2f\u5e38\u898b\u7684\u5bfa\u5edf\u5206\u5225\u4e0d\u5927\uff0c\u6545\u672a\u6709\u518d\u82b1\u9322\u9032\u5167\u53c3\u89c0\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52254\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_11-1024x768.jpg\" alt=\"\" class=\"wp-image-52254\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52255\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_12-1024x768.jpg\" alt=\"\" class=\"wp-image-52255\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"52256\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_13-1024x768.jpg\" alt=\"\" class=\"wp-image-52256\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241113_\u5ee3\u8087\u6703\u9928_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<p>Views: 64<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5728\u9580\u5916\u6240\u898b\uff0c\u5ee3\u8087\u6703\u9928\u7684\u9580\u724c\u574a\u3001\u706b\u5f62\u7684\u5c71\u7246\uff0c\u4ee5\u53ca\u6b63\u810a\u4e0a\u7684\u300c\u96d9\u9f8d\u722d\u73e0\u300d\u9676\u98fe\uff0c\u8207\u9999\u6e2f\u5e38\u898b\u7684\u5bfa\u5edf\u5206\u5225\u4e0d\u5927<\/p>\n","protected":false},"author":1,"featured_media":52251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[130,128],"tags":[],"class_list":["post-52243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024_","category-128"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/52243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=52243"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/52243\/revisions"}],"predecessor-version":[{"id":52257,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/52243\/revisions\/52257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/52251"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=52243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=52243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=52243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}