{"id":53595,"date":"2024-12-23T22:41:07","date_gmt":"2024-12-23T14:41:07","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=53595"},"modified":"2024-12-23T22:41:08","modified_gmt":"2024-12-23T14:41:08","slug":"20241102_50%e9%a6%99%e6%b8%af%e8%a1%8c%e4%b9%8b%e4%b8%ad%e9%9b%bb%e9%90%98%e6%a8%93%e6%96%87%e5%8c%96%e9%a4%a8%e7%9f%ad%e7%89%87%e9%80%a3%e7%b5%90","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/53595\/","title":{"rendered":"20241102_50+\u9999\u6e2f\u884c\u4e4b\u4e2d\u96fb\u9418\u6a13\u6587\u5316\u9928\u77ed\u7247\u9023\u7d50"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>20241102_50+\u9999\u6e2f\u884c\u4e4b\u4e2d\u96fb\u9418\u6a13\u6587\u5316\u9928\u77ed\u7247_01<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_89637\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/rjDhLaf5pLo?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>20241102_50+\u9999\u6e2f\u884c\u4e4b\u4e2d\u96fb\u9418\u6a13\u6587\u5316\u9928\u77ed\u7247_02<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_94945\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/8GhWYnx8xl0?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>20241102_50+\u9999\u6e2f\u884c\u4e4b\u4e2d\u96fb\u9418\u6a13\u6587\u5316\u9928\u77ed\u7247_03<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_11146\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/RMkuf_4aJvk?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n<p>Views: 36<\/p>","protected":false},"excerpt":{"rendered":"<p>20241102_50+\u9999\u6e2f\u884c\u4e4b\u4e2d\u96fb\u9418\u6a13\u6587\u5316\u9928\u77ed\u7247\u9023\u7d50<\/p>\n","protected":false},"author":1,"featured_media":53541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[130,128],"tags":[],"class_list":["post-53595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024_","category-128"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/53595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=53595"}],"version-history":[{"count":1,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/53595\/revisions"}],"predecessor-version":[{"id":53596,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/53595\/revisions\/53596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/53541"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=53595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=53595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=53595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}