{"id":54480,"date":"2025-02-03T20:42:04","date_gmt":"2025-02-03T12:42:04","guid":{"rendered":"https:\/\/50pluslifestories.synology.me\/wordpress\/?p=54480"},"modified":"2025-04-15T10:03:26","modified_gmt":"2025-04-15T02:03:26","slug":"20241227_50%e5%8c%97%e4%ba%ac%e8%a1%8c%e7%ac%ac%e5%9b%9b%e5%a4%a9%e4%b9%8b%e5%8c%97%e6%b5%b7%e5%85%ac%e5%9c%92%e4%b9%9d%e9%be%8d%e5%a3%81","status":"publish","type":"post","link":"https:\/\/50pluslifestories.synology.me\/wordpress\/2024%e5%b9%b4\/54480\/","title":{"rendered":"20241227_50+\u5317\u4eac\u884c\u7b2c\u56db\u5929\u4e4b\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1"},"content":{"rendered":"\n<p class=\"has-cyan-bluish-gray-background-color has-background\">\u5317\u6d77\u516c\u5712\u4f54\u5730\u6975\u70ba\u5ee3\u95ca\uff0c\u7d04\u670970\u516c\u9803\u9762\u7a4d\uff0c\u5176\u4e2d\u4e00\u534a\u662f\u6d41\u6c34\u4e0d\u65b7\u7684\u592a\u6db2\u6c60\u3002\u525b\u65bc\u74ca\u83ef\u5cf6\u7684\u300c\u767d\u5854\u300d\u4e0b\u4f86\uff0c\u82e5\u91cd\u8fd4\u6771\u5074\u6cb3\u7554\u884c\u7684\u4eba\u8def\u671d\u5317\u884c\uff0c\u7d93\u904e\u8173\u8e0f\u8239\u78bc\u982d\uff0c\u4f86\u5230\u5317\u6d77\u516c\u5712\u7684\u6700\u5317\u7aef\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54481\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_01-1024x768.jpg\" alt=\"\" class=\"wp-image-54481\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_01-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_01-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_01-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_01.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54482\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_02-1024x768.jpg\" alt=\"\" class=\"wp-image-54482\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_02-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_02-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_02-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_02.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54483\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_03-1024x768.jpg\" alt=\"\" class=\"wp-image-54483\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_03-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_03-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_03-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_03.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54484\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_04-1024x768.jpg\" alt=\"\" class=\"wp-image-54484\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_04-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_04-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_04-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_04.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54485\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_05-1024x768.jpg\" alt=\"\" class=\"wp-image-54485\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_05-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_05-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_05-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_05.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background\">\u7a7f\u904e\u8de8\u6e56\u884c\u4eba\u5929\u6a4b\uff0c\u524d\u65b9\u662f\u516c\u5712\u5317\u9762\u7684\u9032\u51fa\u53e3\uff0c\u7e5e\u5f80\u897f\u8d70\uff0c\u5728\u59cb\u5efa\u65bc\u6e05\u4e7e\u9686\u4e8c\u5341\u4e00\u5e74\u7684\u975c\u5fc3\u9f4b\uff0c\u4ee5\u53ca\u897f\u5929\u68b5\u5883\uff0c\u4e26\u6c92\u6709\u96a8\u4e00\u773e\u8eab\u7a7f\u6e05\u88dd\u670d\u7684\u5c11\u5973\u4ed8\u8cbb\u9032\u5167\u62cd\u7167\uff0c\u7e7c\u7e8c\u524d\u884c\uff0c\u6700\u5f8c\u4f86\u5230\u5317\u6d77\u7684\u4e5d\u9f8d\u58c1\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54491\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_11-1024x768.jpg\" alt=\"\" class=\"wp-image-54491\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_11-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_11-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_11-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_11.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54492\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_12-1024x768.jpg\" alt=\"\" class=\"wp-image-54492\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_12-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_12-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_12-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_12.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54493\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_13-1024x768.jpg\" alt=\"\" class=\"wp-image-54493\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_13-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_13-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_13-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_13.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54494\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_14-1024x768.jpg\" alt=\"\" class=\"wp-image-54494\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_14-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_14-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_14-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_14.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"54495\" src=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_15-1024x768.jpg\" alt=\"\" class=\"wp-image-54495\" srcset=\"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_15-1024x768.jpg 1024w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_15-300x225.jpg 300w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_15-768x576.jpg 768w, https:\/\/50pluslifestories.synology.me\/wordpress\/wp-content\/uploads\/20241227_\u5317\u6d77\u516c\u5712\u4e5d\u9f8d\u58c1_15.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background\">\u5317\u6d77\u4e5d\u9f8d\u58c1\u5efa\u65bc\u4e7e\u9686\u4e8c\u5341\u4e00\u5e74\uff081756\u5e74\uff09\uff0c\u8ddd\u4eca\u5df2\u6709200\u591a\u5e74\u6b77\u53f2\uff0c\u662f\u4e00\u500b\u7531\u5f69\u8272\u7409\u7483\u78da\u5806\u780c\u800c\u6210\uff0c\u95ca25.86\u7c73\uff0c\u9ad86.65\u7c73\uff0c\u539a1.42\u7c73\u7684\u5de8\u578b\u5f71\u58c1\uff0c\u4e26\u63a1\u7528\u4e2d\u570b\u50b3\u7d71\u5efa\u7bc9\u98a8\u683c\uff0c\u8a2d\u6709\u5ee1\u6bbf\u9802\u548c\u9752\u767d\u7389\u77f3\u53f0\u57fa\uff0c\u800c\u524d\u5f8c\u5247\u5404\u6709\u4e5d\u689d\u9a30\u96f2\u99d5\u9727\u7684\u5f69\u9f8d\uff0c\u6e38\u8d70\u5728\u4e03\u5f69\u7409\u7483\u78da\u9593\uff0c\u6c23\u52e2\u4e0d\u51e1\u3002<\/p>\n<p>Views: 46<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5317\u6d77\u4e5d\u9f8d\u58c1\u5efa\u65bc\u4e7e\u9686\u4e8c\u5341\u4e00\u5e74\uff081756\u5e74\uff09\uff0c\u8ddd\u4eca\u5df2\u6709200\u591a\u5e74\u6b77\u53f2<\/p>\n","protected":false},"author":1,"featured_media":54493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[130,128],"tags":[],"class_list":["post-54480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024_","category-128"],"_links":{"self":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/54480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/comments?post=54480"}],"version-history":[{"count":2,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/54480\/revisions"}],"predecessor-version":[{"id":56264,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/posts\/54480\/revisions\/56264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media\/54493"}],"wp:attachment":[{"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/media?parent=54480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/categories?post=54480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50pluslifestories.synology.me\/wordpress\/wp-json\/wp\/v2\/tags?post=54480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}